{"id":18678,"date":"2024-04-11T10:11:35","date_gmt":"2024-04-11T14:11:35","guid":{"rendered":"https:\/\/www.uqar.ca\/personnes\/jacynthe-dufour\/"},"modified":"2026-09-02T18:15:58","modified_gmt":"2026-09-02T22:15:58","slug":"dufour-jacynthe","status":"publish","type":"personnes","link":"https:\/\/www.uqar.ca\/en\/professeurs\/dufour-jacynthe\/","title":{"rendered":"Jacynthe Dufour"},"content":{"rendered":"\n<section class=\"wp-block-stereo-section-bloc section-block-small -section-block-padding-sm\" data-stereo-anchor-name=\"\"><div class=\"wp-block-stereo-section__container\"><div class=\"wp-block-stereo-section__col is-layout-flow wp-block-stereo-section-bloc-is-layout-flow\">\n<div class=\"wp-block-create-block-accordion-block\"><div class=\"c-tabs\" data-module=\"Tabs\"><div class=\"c-tabs-nav__wrap\" role=\"tablist\"><div class=\"c-tabs-nav-mobile\"><button data-tabs=\"button\" tabindex=\"0\" data-tabs-dir=\"<\" class=\"c-tabs-nav-mobile__button\" role=\"tab\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-left\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg#arrow-left\"><\/use><\/svg><\/button><button data-tabs=\"button\" tabindex=\"0\" data-tabs-dir=\"&gt;\" class=\"c-tabs-nav-mobile__button\" role=\"tab\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-right\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg#arrow-right\"><\/use><\/svg><\/button><\/div><div class=\"c-tabs-nav\" data-tabs=\"nav\"><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Domaines de recherche<\/span><\/button><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Recherches et expertises<\/span><\/button><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Publications et communications<\/span><\/button><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Cours enseign\u00e9s<\/span><\/button><\/div><\/div><div class=\"c-tabs-content__wrap\">\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\"><p>\n    <ul>\n        <li>Pratique infirmi\u00e8re avanc\u00e9e<\/li><li>D\u00e9marche et raisonnement clinique<\/li><li>\u00c9valuation clinique de l\u2019enfant, adulte, personne \u00e2g\u00e9e<\/li><li>Suivi des maladies chroniques<\/li><li>Contraception<\/li>    <\/ul>\n<\/p><\/div><\/div>\n\n\n\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\">\n<div class=\"wp-block-create-block-accordion-block\"><div class=\"c-accordion\" data-module=\"Accordion\" data-accordion-toggle=\"true\" data-accordion-scroll=\"true\" data-accordion-preopen=\"-1\">\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Formation\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"formation\"><span class=\"c-accordion__button\"> Formation<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Maitrise en sciences infirmi\u00e8res (soins de premi\u00e8re ligne) (2012)<br>DESS en pratique sp\u00e9cialis\u00e9e en soins de premi\u00e8re ligne<br>Universit\u00e9 Laval<\/li>\n\n\n\n<li>Maitrise en sciences infirmi\u00e8res avec m\u00e9moire (2007)<br>Universit\u00e9 Laval<br>\u00c9tude exploratoire sur la pratique infirmi\u00e8re avanc\u00e9e en soins de premi\u00e8re ligne en milieu d\u2019urgence<\/li>\n\n\n\n<li>Baccalaur\u00e9at en sciences infirmi\u00e8res (2002)<br>Universit\u00e9 Laval<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Prix et distinctions\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"prix-et-distinctions\"><span class=\"c-accordion__button\"> Prix et distinctions<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<h4 class=\"wp-block-heading has--color has-text-color\">LITTORIADES (CISSS du Grand Littoral)<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prix qualit\u00e9 rel\u00e8ve 2010<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">UNIVERSIT\u00c9 LAVAL<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">TABLEAU D\u2019HONNEUR DE LA FACULT\u00c9 DES SCIENCES INFIRMI\u00c8RES<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00e9rite acad\u00e9mique 2007-2008<\/li>\n\n\n\n<li>M\u00e9rite acad\u00e9mique 2012-2013<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Projets de recherche\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"projets-de-recherche\"><span class=\"c-accordion__button\"> Projets de recherche<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<p class=\"wp-block-paragraph\">\u00c0 venir<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Supervision d'\u00e9tudiants de cycles sup\u00e9rieurs\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"supervision-detudiants-de-cycles-superieurs\"><span class=\"c-accordion__button\"> Supervision d&#8217;\u00e9tudiants de cycles sup\u00e9rieurs<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<p class=\"wp-block-paragraph\">\u00c0 venir<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Exp\u00e9rience professionnelle\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"experience-professionnelle\"><span class=\"c-accordion__button\"> Exp\u00e9rience professionnelle<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<h4 class=\"wp-block-heading has--color has-text-color\">CISSS de Chaudi\u00e8re-Appalaches (CISSSCA), <em>L\u00e9vis<\/em><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Infirmi\u00e8re praticienne sp\u00e9cialis\u00e9e en soins de premi\u00e8re ligne<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Autres activit\u00e9s\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"autres-activites\"><span class=\"c-accordion__button\"> Autres activit\u00e9s<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<h4 class=\"wp-block-heading has--color has-text-color\">ORIICA<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">VICE-PR\u00c9SIDENCE<\/p>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">OIIQ<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>MEMBRE COMIT\u00c9 DE L\u2019EXAMEN DE CERTIFICATION DES IPS<\/li>\n\n\n\n<li>FORMATRICE EXPERTE<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">PROJET AVENTURE MEDECINE<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Membre comit\u00e9 collaboration interprofessionnelle au 2ᵉ cycle<\/p>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">Adaptatrice&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Lowdermilk, D.L., Perry, S. &amp; Cashion, K. (2018). Soins infirmiers P\u00e9rinatalit\u00e9. Cheneli\u00e8re \u00c9ducation. 2<sup>e<\/sup>&nbsp;\u00e9dition<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Affiliations\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"affiliations\"><span class=\"c-accordion__button\"> Affiliations<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Membre de l\u2019Ordre des infirmi\u00e8res et infirmiers du Qu\u00e9bec<\/li>\n\n\n\n<li>Membre de l\u2019Association des infirmi\u00e8res praticiennes sp\u00e9cialis\u00e9es du Qu\u00e9bec<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\">\n<div class=\"wp-block-create-block-accordion-block\"><div class=\"c-accordion\" data-module=\"Accordion\" data-accordion-toggle=\"true\" data-accordion-scroll=\"true\" data-accordion-preopen=\"-1\">\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Publications\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"publications\"><span class=\"c-accordion__button\"> Publications<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<p class=\"wp-block-paragraph\">\u00c0 venir<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Communications\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"communications\"><span class=\"c-accordion__button\"> Communications<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<p class=\"wp-block-paragraph\">\u00c0 venir<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\">\n    <p><strong>Premier cycle :<\/strong><\/p>\n    <ul>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">SSN24203<\/a> \u00c9valuation clinique de l&#8217;adulte<\/li>\n            <\/ul>\n    <p><strong>Deuxi\u00e8me cycle :<\/strong><\/p>\n    <ul>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">MSI6093<\/a> \u00c9valuation clinique des adultes et des personnes \u00e2g\u00e9es<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">MSI6140<\/a> R\u00f4le de l&#8217;infirmi\u00e8re en pratique avanc\u00e9e<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">MSI6302<\/a> Interventions \u00e9ducatives en sant\u00e9<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">MSI6310<\/a> Enjeux de la pratique infirmi\u00e8re avanc\u00e9e<\/li>\n            <\/ul>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/section>\n","protected":false},"featured_media":80655,"template":"","departement_personnes":[263],"class_list":["post-18678","personnes","type-personnes","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes\/18678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes"}],"about":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/types\/personnes"}],"version-history":[{"count":9,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes\/18678\/revisions"}],"predecessor-version":[{"id":80659,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes\/18678\/revisions\/80659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/media\/80655"}],"wp:attachment":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/media?parent=18678"}],"wp:term":[{"taxonomy":"departement_personnes","embeddable":true,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/departement_personnes?post=18678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}