{"id":18756,"date":"2024-04-11T10:12:19","date_gmt":"2024-04-11T14:12:19","guid":{"rendered":"https:\/\/www.uqar.ca\/personnes\/nancy-michaud\/"},"modified":"2026-09-01T18:16:36","modified_gmt":"2026-09-01T22:16:36","slug":"michaud-nancy","status":"publish","type":"personnes","link":"https:\/\/www.uqar.ca\/en\/professeurs\/michaud-nancy\/","title":{"rendered":"Nancy Michaud"},"content":{"rendered":"\n<section class=\"wp-block-stereo-section-bloc section-block-small -section-block-padding-sm\" data-stereo-anchor-name=\"\"><div class=\"wp-block-stereo-section__container\"><div class=\"wp-block-stereo-section__col is-layout-flow wp-block-stereo-section-bloc-is-layout-flow\">\n<div class=\"wp-block-create-block-accordion-block\"><div class=\"c-tabs\" data-module=\"Tabs\"><div class=\"c-tabs-nav__wrap\" role=\"tablist\"><div class=\"c-tabs-nav-mobile\"><button data-tabs=\"button\" tabindex=\"0\" data-tabs-dir=\"<\" class=\"c-tabs-nav-mobile__button\" role=\"tab\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-left\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg#arrow-left\"><\/use><\/svg><\/button><button data-tabs=\"button\" tabindex=\"0\" data-tabs-dir=\"&gt;\" class=\"c-tabs-nav-mobile__button\" role=\"tab\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-right\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg#arrow-right\"><\/use><\/svg><\/button><\/div><div class=\"c-tabs-nav\" data-tabs=\"nav\"><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Domaines de recherche<\/span><\/button><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Recherches et expertises<\/span><\/button><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Publications et communications<\/span><\/button><button class=\"c-tabs-nav__item\" data-tabs=\"trigger\" role=\"tab\"><span class=\"c-tab\">Cours enseign\u00e9s<\/span><\/button><\/div><\/div><div class=\"c-tabs-content__wrap\">\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\"><p>\n    <ul>\n        <li>Audit et certification<\/li><li>Jugement professionnel (processus et d\u00e9veloppement)<\/li><li>\u00c9tude des savoirs d\u2019exp\u00e9rience<\/li><li>\u00c9thique professionnelle<\/li><li>Entretien d&#8217;explicitation<\/li><li>Autoprax\u00e9ographie<\/li><li>Gouvernance et innovation dans les services de sant\u00e9<\/li><li>Transformation num\u00e9rique au sein des organisations<\/li><li>D\u00e9veloppement de la comp\u00e9tence num\u00e9rique au post secondaire<\/li><li>Transition vers les \u00e9tudes post secondaires<\/li>    <\/ul>\n<\/p><\/div><\/div>\n\n\n\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\">\n<div class=\"wp-block-create-block-accordion-block\"><div class=\"c-accordion\" data-module=\"Accordion\" data-accordion-toggle=\"true\" data-accordion-scroll=\"true\" data-accordion-preopen=\"-1\">\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Formation\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"formation\"><span class=\"c-accordion__button\"> Formation<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Doctorat en sciences de gestion, Universit\u00e9 Bourgogne Franche-Comt\u00e9 (FRANCE) (2021)<\/li>\n\n\n\n<li>Microprogramme de 3ᵉ cycle en p\u00e9dagogie de l&#8217;enseignement sup\u00e9rieur, Universit\u00e9 de Sherbrooke (en cours)<\/li>\n\n\n\n<li>M.B.A. option comptabilit\u00e9, Universit\u00e9 Laval (2010)<\/li>\n\n\n\n<li>D.E.S.S. en sciences comptables, Universit\u00e9 du Qu\u00e9bec \u00e0 Rimouski (2001)<\/li>\n\n\n\n<li>Baccalaur\u00e9at en sciences comptables (expertise comptable), Universit\u00e9 du Qu\u00e9bec \u00e0 Rimouski (2000)<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">Autre formation<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Conservatoire de musique de Rimouski (Programme externe : 8e degr\u00e9, Violon) (2019)<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Projets de recherche en cours et subventions\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"projets-de-recherche-en-cours-et-subventions\"><span class=\"c-accordion__button\"> Projets de recherche en cours et subventions<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<p class=\"wp-block-paragraph\"><strong>Co-chercheuse&nbsp;pour le projet intitul\u00e9 \u00ab&nbsp; \u00bb. Projet financ\u00e9 par le CRSH concours Nouvelles Fronti\u00e8res \u2013 recherche pour la reprise postpand\u00e9mique 2023-2026.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Chercheuse principale&nbsp;: Genevi\u00e8ve McCready.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Projet de recherche qui vise l\u2019\u00e9tude du savoir pratique de l\u2019auditeur externe et l\u2019exercice de son jugement professionnel<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Projet financ\u00e9 par la Fondation des CPA du Qu\u00e9bec. Th\u00e8se soutenue avec succ\u00e8s. Diff\u00e9rents articles sont en cours de r\u00e9daction.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Chercheure invit\u00e9e<\/strong> au sein du<strong> Groupe de recherche et d\u2019innovation sur l\u2019organisation des services de sant\u00e9 <\/strong>(GRIOSS) de<strong> l\u2019Universit\u00e9 de Moncton :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comment les dynamiques entre les acteurs d\u2019une gouverne en r\u00e9seau orientent-elles l\u2019apparition d\u2019innovations sociales \u00e0 l\u2019\u00e9gard de l\u2019acc\u00e8s aux services de sant\u00e9 pour les communaut\u00e9s francophones en situation minoritaire? Projet financ\u00e9 par la FINB et l\u2019ACFAS (programme de coop\u00e9ration en recherche dans la francophonie canadienne)<\/li>\n\n\n\n<li>Immigrants francophones en r\u00e9gion rurale et francophone du Nouveau-Brunswick : exp\u00e9rience migratoire et communaut\u00e9 d\u2019accueil<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Parcours r\u00e9ussi vers les \u00e9tudes sup\u00e9rieures : un d\u00e9fi interordres<\/strong><br>Projet financ\u00e9 par le Minist\u00e8re de l\u2019Enseignement Sup\u00e9rieur (MES)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Responsable du chantier r\u00e9gional au CEGEP de Rimouski (techniques administratives) et \u00e0 l\u2019UQAR (baccalaur\u00e9at en administration et en sciences comptables). Le projet vise la transition au niveau de la comp\u00e9tence num\u00e9rique entre les ordres d\u2019enseignement.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Supervision d'\u00e9tudiants de cycles sup\u00e9rieurs\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"supervision-detudiants-de-cycles-superieurs\"><span class=\"c-accordion__button\"> Supervision d&#8217;\u00e9tudiants de cycles sup\u00e9rieurs<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<h4 class=\"wp-block-heading has--color has-text-color\">Supervision de m\u00e9moire \u00e0 la maitrise en gestion de projet \u2013 en cours<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Agatha\u00eblle Dorsainvil \u00ab Exploration de la gestion de projet en milieu organisationnel : D\u00e9fis et strat\u00e9gies d\u2019adaptations des gestionnaires de projet. Cas d\u2019une entreprise de recherche appliqu\u00e9e du Bas St-Laurent \u00bb. (Titre provisoire)<\/li>\n\n\n\n<li>Kervens Zamor \u00ab \u00c9tude de la gestion des parties prenantes dans la gestion d\u2019un projet de recherche-action participative dans le domaine du care au Qu\u00e9bec. \u00bb (Titre provisoire)<\/li>\n\n\n\n<li>\u00c9milie Rancourt Ayotte \u00ab&nbsp;Le financement des projets chez les tr\u00e8s petits entrepreneurs au nord du Nouveau-Brunswick. \u00bb.<\/li>\n\n\n\n<li>Francisco Nieto Melgarejo \u00ab&nbsp;Gestion de la capacit\u00e9 en contexte de p\u00e9nurie de main d&#8217;\u0153uvre : \u00e9tude de cas au sein de Revenu Qu\u00e9bec&nbsp;\u00bb.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">Supervision de projets compl\u00e9t\u00e9s dans le cadre du cours&nbsp;SCO70116 Activit\u00e9 de synth\u00e8se,&nbsp;pr\u00e9vu \u00e0 la ma\u00eetrise par cumul en sciences comptables<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Myriam Desjardins (2023) \u00ab&nbsp;L\u2019int\u00e9gration du capital humain dans les demandes de subvention &#8211; \u00c9tude de cas sur les al\u00e9as r\u00e9els pour l\u2019obtention d\u2019une subvention extraordinaire\u00bb.<\/li>\n\n\n\n<li>Martin Ouellet (2022) \u00ab L\u2019exercice du jugement en contexte de contr\u00f4le interne : Le cas du CISSS du BSL \u00bb.<\/li>\n\n\n\n<li>Zohra Fawaz (2021) \u00ab&nbsp;R\u00e9percussions de la pand\u00e9mie&nbsp;: le t\u00e9l\u00e9travail et son avenir \u00bb. Codirection effectu\u00e9e avec la professeure Anne-Louise Caron.<\/li>\n\n\n\n<li>Marie-Philippe Savard (2020) \u00ab&nbsp;Transfert d\u2019entreprise&nbsp;: quels sont les \u00e9tapes et les principaux enjeux du point de vue du repreneur&nbsp;\u00bb.<\/li>\n\n\n\n<li>Audrey Bergeron (2020) \u00ab&nbsp;Difficult\u00e9s financi\u00e8res d\u2019entreprises&nbsp;: quand agir, les options, les conditions de succ\u00e8s et l\u2019entrepreneur \u00bb.<\/li>\n\n\n\n<li>\u00c9dith B\u00e9langer (2019) \u00ab&nbsp;Comprendre les liens entre l\u2019\u00e9ducation financi\u00e8re aupr\u00e8s des jeunes \u00ab C\u00e9g\u00e9piens\u00bb, la litt\u00e9ratie financi\u00e8re et leurs comportements financiers&nbsp;\u00bb.<\/li>\n\n\n\n<li>\u00c9milie Roussel (2019) \u00ab&nbsp;La mobilisation des employ\u00e9s d\u2019un cabinet comptable afin de diminuer le taux de roulement. \u00bb.<\/li>\n\n\n\n<li>Jean-Nicolas St-Pierre (2018) \u00ab&nbsp;La d\u00e9termination du contr\u00f4le conjoint en pratique chez les entit\u00e9s utilisant les normes comptables pour les entreprises \u00e0 capital ferm\u00e9.&nbsp;\u00bb. Codirection effectu\u00e9e avec le professeur Rodrigue Proulx.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading has--color has-text-color\">Supervision de projets en cours dans le cadre du cours&nbsp;SCO70116 Activit\u00e9 de synth\u00e8se,&nbsp;pr\u00e9vu \u00e0 la ma\u00eetrise par cumul en sciences comptables<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Anne-Marie Cabot \u00ab&nbsp;Parcours et r\u00e9tention des comptables professionnels agr\u00e9\u00e9s (CPA) \u00e9voluant en cabinet comptable. (Titre provisoire) \u00bb<\/li>\n\n\n\n<li>Dany Renaud \u00ab&nbsp;R\u00e9flexion sur la transformation num\u00e9rique au sein de la soci\u00e9t\u00e9. (Titre provisoire) \u00bb<\/li>\n\n\n\n<li>Laurie St-Pierre \u00ab&nbsp;La conciliation travail-famille pour les m\u00e8res CPA en cabinet.&nbsp;\u00bb<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Autres activit\u00e9s\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"autres-activites\"><span class=\"c-accordion__button\"> Autres activit\u00e9s<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Membre du groupe de Co-d\u00e9veloppement en sciences de la gestion de l\u2019UQAR<\/li>\n\n\n\n<li>Membre du conseil d\u2019administration de la Soci\u00e9t\u00e9 des concerts Bic-St-Fabien (depuis 2007)<\/li>\n\n\n\n<li>B\u00e9n\u00e9vole pour l\u2019Orchestre Symphonique de l\u2019Estuaire et le Festi-Jazz de Rimouski<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Exp\u00e9rience professionnelle\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"experience-professionnelle\"><span class=\"c-accordion__button\"> Exp\u00e9rience professionnelle<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Banque de d\u00e9veloppement du Canada &#8211; Directrice de comptes au d\u00e9veloppement des affaires (2006-2009)<\/li>\n\n\n\n<li>Mallette, S.E.N.C.R.L. &#8211; V\u00e9rificatrice senior (2000-2006)<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Affiliations\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"affiliations\"><span class=\"c-accordion__button\"> Affiliations<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Membre de l\u2019Association Francophone de Comptabilit\u00e9 (AFC)<\/li>\n\n\n\n<li>Comptable professionnelle agr\u00e9\u00e9e, auditrice (CPA auditrice) (depuis 2003)<\/li>\n\n\n\n<li>Membre r\u00e9guli\u00e8re au sein de de l\u2019Unit\u00e9 mixte de recherche (UMR) INRS-UQAR sur la Transformation num\u00e9rique en appui au d\u00e9veloppement r\u00e9gional.<\/li>\n\n\n\n<li>Membre du groupe de recherche ETHOS, UQAR<\/li>\n\n\n\n<li>Chercheuse invit\u00e9e au sein du groupe de recherche et d\u2019innovation sur l\u2019organisation des services de sant\u00e9 (GRIOSS), Universit\u00e9 de Moncton<\/li>\n\n\n\n<li>Agente de liaison et membre de l&#8217;Association canadienne des professeurs de comptabilit\u00e9 (ACPC)<\/li>\n\n\n\n<li>Membre du R\u00e9seau de praticiens et de chercheurs de la FADIO (Formation \u00e0 distance interordres)<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\">\n<div class=\"wp-block-create-block-accordion-block\"><div class=\"c-accordion\" data-module=\"Accordion\" data-accordion-toggle=\"true\" data-accordion-scroll=\"true\" data-accordion-preopen=\"-1\">\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Publications\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"publications\"><span class=\"c-accordion__button\"> Publications<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li>Parent, S., Desch\u00eanes, M., Dionne, L., Gonthier, M-E., Jolicoeur, E, <strong>Michaud, N.<\/strong> &amp; Desmeules-Th\u00e9riault, G. (2024). D\u00e9veloppement de la comp\u00e9tence num\u00e9rique interordres (CNIO), Rapport de recherche du regroupement BSLGIM, Dans le cadre du projet <em>Transitions r\u00e9ussies vers les \u00e9tudes sup\u00e9rieures : un d\u00e9fi interordres<\/em>.<br><\/li>\n\n\n\n<li>Collin, S., <strong>Michaud, N.<\/strong> et Ringuette, C. (2024) \u00ab Une innovation r\u00e9ussie et durable au sein d\u2019un r\u00e9seau de sant\u00e9, soit un h\u00f4pital et centre de sant\u00e9 communautaire en r\u00e9gion rurale au Canada \u00bb, Revue francophone sur la sant\u00e9 et les territoires [En ligne], D\u00e9centralisation et territorialisation sanitaire, mis en ligne le 12 mars 2024; <a href=\"http:\/\/journals.openedition.org\/rfst\/2025\"><\/a><a href=\"http:\/\/journals.openedition.org\/rfst\/2025\">http:\/\/journals.openedition.org\/rfst\/2025<\/a>;<br><\/li>\n\n\n\n<li><strong>Michaud, Nancy<\/strong> et Couture, Marie-Mich\u00e8le (2023). L\u2019humanit\u00e9 du comptable : une \u00e9tude en complexit\u00e9 \u00bb, Revue Interventions \u00e9conomiques [En ligne], vol. 69 URL : <a href=\"http:\/\/journals.openedition.org\/interventionseconomiques\/23216\"><\/a><a href=\"http:\/\/journals.openedition.org\/interventionseconomiques\/23216\">http:\/\/journals.openedition.org\/interventionseconomiques\/23216<\/a><\/li>\n\n\n\n<li>Demers, S., Veilleux, M., Parent, S., <strong>Michaud, N.<\/strong>, B\u00e9lec, C., Staiculescu, R. et Desjardins, F. (2023). Continuum de d\u00e9veloppement des comp\u00e9tences essentielles aux \u00e9tudes sup\u00e9rieures (CDCEES).<\/li>\n\n\n\n<li>Albert, M. N., Dodeler, N. L., Couture, M. M., &amp; <strong>Michaud, N<\/strong>. (2023). L\u2019autoprax\u00e9ographie, une m\u00e9thode pour construire des savoirs \u00e0 partir de son exp\u00e9rience dans une perspective complexe et interdisciplinaire. Journal of Interdisciplinary Methodologies and Issues in Sciences, 11(Domaine 1: L&#8217;interdisciplinarit\u00e9 comme champ de recherche).<\/li>\n\n\n\n<li>Albert, M. N., &amp; <strong>Michaud, N.<\/strong> (2023). Autopraxeography: a method to step back from vulnerability. Journal of Work-Applied Management, 15(1), 67-80.<\/li>\n\n\n\n<li><strong>Michaud, Nancy<\/strong> (2021). \u00ab Savoir pratique de l\u2019auditeur externe et l\u2019exercice de son jugement professionnel \u00bb, Th\u00e8se doctorale publi\u00e9e, sous la direction de Monsieur Benoit Pig\u00e9, Universit\u00e9 de Bourgogne Franche-Comt\u00e9, Besan\u00e7on, France<\/li>\n\n\n\n<li>Albert, M.-N., <strong>Michaud, N.<\/strong>, Lazzari Dodeler, N.; Caron, A.-L., El Fadil, J., Fissette, S. et Michaud, C. (2021). \u00ab Chapitre 15 : Le cod\u00e9veloppement en p\u00e9dagogie universitaire : un projet commun pour sortir de l\u2019isolement dans le cas de situations complexes \u00bb, contribution \u00e0 l\u2019ouvrage intitul\u00e9 \u00ab Entreprendre et innover dans les formations \u00e0 l\u2019Universit\u00e9 \u00bb, sous la direction de Elisabeth Deschanet, Ilias Majdouline et Christophe Schmitt, Organisations en action, PUN &#8211; \u00c9ditions Universitaires de Lorraine.<\/li>\n\n\n\n<li>Albert, Marie-No\u00eblle et <strong>Nancy Michaud<\/strong> (2020). Chapitre 12 \u00ab&nbsp;Les utilisations de l\u2019autoprax\u00e9ographie pour le dirigeant-chercheur&nbsp;\u00bb au sein de l\u2019ouvrage \u00ab&nbsp;Produire du savoir et de l\u2019action&nbsp;\u00bb, \u00c9dition EMS, 249 pages<\/li>\n\n\n\n<li>Albert, M. N., &amp; <strong>Michaud, N.<\/strong> (2016). From Disillusion to the Development of Professional Judgment: Experience of the Implementation Process of a Human Complexity Course. <i style=\"background-color: initial; font-size: 1em;\">SAGE Open<\/i><span style=\"background-color: initial; font-size: 1em;\">, <\/span><i style=\"background-color: initial; font-size: 1em;\">6<\/i><span style=\"background-color: initial; font-size: 1em;\">(4), 2158244016684372.<\/span><\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> (2016). \u00ab&nbsp;Conscientiser le savoir pratique impliqu\u00e9 dans le jugement professionnel lors de l\u2019audit des \u00e9tats financiers\u00bb, <a href=\"https:\/\/www.uqar.ca\/universite\/a-propos-de-l-uqar\/departements\/departement-de-psychosociologie-et-travail-social\/presences-revue-transdisciplinaire-d-etude-des-pratiques-psychosociales\" style=\"background-color: initial; font-size: 1em;\">Pr\u00e9sences<\/a><span style=\"background-color: initial; font-size: 1em;\">, vol. 9.<\/span><\/li>\n\n\n\n<li>Projet inter-ordres T\u00c9LUQ, UQAR, coll\u00e8ge Montmorency, c\u00e9gep de Rimouski et C\u00e9gep@distance, (2015)&nbsp;<i>Des outils multim\u00e9dia en ligne pour soutenir les apprentissages en comptabilit\u00e9 au coll\u00e9gial et \u00e0 l\u2019universit\u00e9<\/i>,&nbsp;http:\/\/perseverance.savie.ca.<\/li>\n\n\n\n<li><strong>MICHAUD, N.<\/strong>, &#8220;Les pr\u00e9visions financi\u00e8res, le financement et la comptabilit\u00e9&#8221;, R\u00e9pertoire des essais de la facult\u00e9 des sciences de l&#8217;administration de l&#8217;Universit\u00e9 Laval, sous la supervision de Madame \u00c9lise Cormier, Ph. D., 2010.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"c-accordion__section\" data-accordion=\"wrap\"><button type=\"button\" aria-label=\"Ouvrir  Communications\" class=\"c-accordion__header\" data-accordion=\"trigger\"><span class=\"c-accordion__header__title\" id=\"communications\"><span class=\"c-accordion__button\"> Communications<span class=\"c-accordion__header__icon\"><span class=\"o-button__icon\"><svg aria-hidden=\"true\" focusable=\"false\" class=\"o-ico -icon-arrow-down\"><use xlink:href=\"\/app\/themes\/baserock\/assets\/img\/sprite.svg?v=899ec6baabe4cd8be5?v=899ec6baabe4cd8be5#arrow-down\"><\/use><\/svg><\/span><\/span><\/span><\/span><\/button><div class=\"c-accordion__content\" role=\"region\" data-accordion=\"content\"><div class=\"c-accordion__inner\">\n<ul class=\"wp-block-list\">\n<li><strong>Michaud, N.<\/strong> (2024) \u00ab L\u2019\u00e9tude de la pratique de l\u2019audit: mettre en lumi\u00e8re l\u2019exercice du jugement professionnel \u00bb Dans le cadre du colloque #453 \u00ab Recherche qualitative en comptabilit\u00e9: un espace francophone pour poser un regard sur les (en)jeux comptables au sein des organisations et de la soci\u00e9t\u00e9 \u00bb du 91e Congr\u00e8s de l\u2019ACFAS, Ottawa.<br><\/li>\n\n\n\n<li><strong>Michaud, N. <\/strong>&amp; B\u00e9langer, E. (2024) \u00ab Le processus et les d\u00e9fis de l\u2019int\u00e9gration de la comp\u00e9tence num\u00e9rique lors de la r\u00e9vision d\u2019un programme universitaire \u00bb Dans le cadre du symposium \u00ab \u00c9mergence de la didactique du num\u00e9rique : pratiques inspirantes \u00bb du 11e Colloque international en \u00e9ducation, Montr\u00e9al.<br><\/li>\n\n\n\n<li>Parent, S. &amp; <strong>Michaud, N.<\/strong> (2024) \u00ab \u00c9laboration d\u2019un continuum de d\u00e9veloppement de la comp\u00e9tence num\u00e9rique au postsecondaire un regard r\u00e9flexif \u00bb Dans le cadre du symposium \u00ab \u00c9mergence de la didactique du num\u00e9rique : pratiques inspirantes \u00bb du 11e Colloque international en \u00e9ducation, Montr\u00e9al.<br><\/li>\n\n\n\n<li><strong>Michaud, N.<\/strong>, B\u00e9langer, E. &amp; Gendreau, M. (2023) \u00ab&nbsp;Mesures de soutien au d\u00e9veloppement de la comp\u00e9tence num\u00e9rique (CN) : constats tir\u00e9s d\u2019une recherche au sein des programmes en administration et comptabilit\u00e9 dans une perspective interordres (IO).&nbsp;\u00bb Dans le cadre du symposium \u00ab&nbsp;Identification des mesures de soutien au d\u00e9veloppement de la comp\u00e9tence num\u00e9rique dans des contextes de transition vers les \u00e9tudes sup\u00e9rieures&nbsp;\u00bb du 10e Colloque international en \u00e9ducation, Montr\u00e9al.<br><\/li>\n\n\n\n<li>Albert M.N., Boutet D., Rennie C., <strong>Michaud N.<\/strong> &amp; Castro S. (2023), \u00ab Un projet de doctorat en nouvelles pratiques humaines et sociales : un partenariat entre des disciplines pour favoriser l\u2019innovation \u00bb, Projectique, Agadir.<\/li>\n\n\n\n<li>Collin S., <strong>Michaud N.<\/strong> et Ringuette C. (2022). Des pratiques innovantes visant \u00e0 am\u00e9liorer l\u2019acc\u00e8s aux services et soins de sant\u00e9 pour les CLOSM : la gouvernance collaborative est-elle un \u00ab mal n\u00e9cessaire \u00bb? ACFAS, Colloque 629 \u00ab La sant\u00e9 des francophones en contexte linguistique minoritaire : 20 ans de recherche \u00bb<br><\/li>\n\n\n\n<li>Albert M.N., Lazzari Dodeler N., <strong>Michaud N<\/strong> et Couture M.M. (2022). L\u2019autoprax\u00e9ographie, une m\u00e9thode pour construire des savoirs \u00e0 partir de son exp\u00e9rience dans une perspective complexe et interdisciplinaire, Hutlaconf, Montpellier.<\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;L\u2019entretien d\u2019explicitation de l\u2019action&nbsp;: pertinence et mise en \u0153uvre pour l\u2019\u00e9tude des jugements pos\u00e9s en audit. \u00bb Symposium sur les m\u00e9thodes qualitatives&nbsp;: Audit et gouvernance en contexte, The Canadian Academic Accounting Association (CAAA), Saskatoon, 2022<br><\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;L\u2019utilisation de la technique d\u2019entretien d\u2019explicitation de l\u2019action au sein des cabinets de comptables professionnels&nbsp;: les enjeux v\u00e9cus sur le terrain et les moyens utilis\u00e9s pour r\u00e9ussir sa collecte de donn\u00e9es \u00bb, ACFAS, Colloque 455 \u00ab&nbsp;Les enjeux actuels de l\u2019exp\u00e9rience de terrain&nbsp;: Sur la libert\u00e9, l\u2019autonomie et l\u2019autod\u00e9termination de la recherche sociologique. \u00bb, Universit\u00e9 Laval, Qu\u00e9bec, 2022<br><\/li>\n\n\n\n<li>Collin, S.,<strong> Michaud, N<\/strong>. et Ringuette, C. \u00ab&nbsp;Des pratiques innovantes visant \u00e0 am\u00e9liorer l\u2019acc\u00e8s aux services et soins de sant\u00e9 pour les CLOSM&nbsp;: la gouvernance collaborative est-elle un \u00ab mal n\u00e9cessaire \u00bb?, ACFAS, Colloque 629 \u00ab&nbsp;La sant\u00e9 des francophones en contexte linguistique minoritaire&nbsp;: 20 ans de recherche \u00bb, Universit\u00e9 Laval, Qu\u00e9bec, 2022<br><\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;External auditor&#8217;s practical knowledge and professional judgment. \u00bb Craft on Accounting Workshop, Annual Conference, The Canadian Academic Accounting Association (CAAA), Ottawa, 2019<\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;Savoir pratique de l\u2019auditeur externe et jugement professionnel \u00bb, S\u00e9minaire de recherche, Universit\u00e9 de Franche Comt\u00e9, Besan\u00e7on, 2018<\/li>\n\n\n\n<li>Albert Marie-No\u00eblle &amp; <strong>Nancy Michaud<\/strong> \u00ab&nbsp;The autopraxeography method : what does it mean? \u00bb, Congr\u00e8s de l\u2019European Academy of Management (EURAM), Reykjavik, Islande, 2018<\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;L\u2019enseignement de l\u2019audit au 1<sup>er<\/sup> cycle&nbsp;\u00bb, Congr\u00e8s annuel de l\u2019Association canadienne des professeurs de comptabilit\u00e9, Montr\u00e9al, 2017<\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;Savoir pratique de l\u2019auditeur externe et jugement professionnel\u00bb, ACFAS, Universit\u00e9 McGill, Montr\u00e9al, 2017<\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong> \u00ab&nbsp;L\u2019acc\u00e8s \u00e0 la recherche au sein des cabinets de comptables professionnels&nbsp;: les d\u00e9fis \u00e0 relever et les strat\u00e9gies pour r\u00e9ussir son approche \u00bb, ACFAS, Colloque 25 \u00ab&nbsp;L\u2019acc\u00e8s de la recherche au terrain&nbsp;: processus, contraintes, impacts et strat\u00e9gies&nbsp;\u00bb, Universit\u00e9 McGill, Montr\u00e9al, 2017<br><\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong>, Anne-Louise Caron et Michael Lafontaine \u00ab&nbsp;L\u2019utilisation des \u00ab&nbsp;quiz&nbsp;\u00bb pour favoriser la lecture chez les \u00e9tudiants en sciences comptables&nbsp;: analyse de trois exp\u00e9riences v\u00e9cues diff\u00e9remment\u00bb, ACFAS, Universit\u00e9 McGill, Montr\u00e9al, 2017<\/li>\n\n\n\n<li>Michaud Patricia, Samuel Saint-Yves-Durand, <strong>Nancy Michaud<\/strong> et Anne-Louise Caron \u00ab&nbsp;Cr\u00e9ation d\u2019un outil num\u00e9rique de progression des apprentissages pour les \u00e9tudiants en sciences comptables&nbsp;: une recherche exploratoire\u00bb, ACFAS, Universit\u00e9 McGill, Montr\u00e9al, 2017<\/li>\n\n\n\n<li>Albert Marie-No\u00eblle, <strong>Nancy Michaud<\/strong>, Nadia Lazzari-Dodeler, Anne-Louise Caron, Marie-Mich\u00e8le Couture, Gabrielle Dub\u00e9, St\u00e9phanie Fissette et Collette Michaud \u00ab&nbsp;Des personnes qui enseignent \u00e0 des personnes&nbsp;: groupe de cod\u00e9veloppement et savoirs de l\u2019exp\u00e9rience.&nbsp;\u00bb, Colloque de p\u00e9dagogie universitaire, UQAR, Rimouski, 2015<br><\/li>\n\n\n\n<li><strong>Michaud Nancy<\/strong>, Anne-Louise Caron et Michael Lafontaine \u00ab&nbsp;Nos \u00e9tudiants, comment arriver \u00e0 les faire lire de fa\u00e7on efficace?&nbsp;\u00bb, Rencontre des partenaires \u2013 Formation @ distance interordres, Rimouski, 2015<\/li>\n\n\n\n<li>ALBERT, M.-N. &amp; <strong>MICHAUD, N.<\/strong> &#8220;De la d\u00e9sillusion au d\u00e9veloppement du jugement professionnel: l&#8217;exp\u00e9rience d&#8217;un processus de mise en oeuvre&nbsp;d&#8217;un cours&nbsp;sur la&nbsp;complexit\u00e9 humaine&#8221;, ACFAS, Rimouski, 2015<\/li>\n\n\n\n<li>Lafontaine Michael, Claude Galaise, Bruce Lagrange et <strong>Nancy Michaud<\/strong> \u00ab&nbsp;L\u2019apprentissage en profondeur&nbsp;\u00bb, Colloque de p\u00e9dagogie universitaire, UQAR, Rimouski, 2013<\/li>\n\n\n\n<li>LAFONTAINE, M., GALAISE, C., <strong>MICHAUD, N.<\/strong> &amp; LAGRANGE, B., &#8220;Contribuer \u00e0 la r\u00e9ussite professionnelle des dipl\u00f4m\u00e9s par l&#8217;apprentissage en profondeur&#8221;, Colloque international de p\u00e9dagogie universitaire AIPU, Trois-Rivi\u00e8res, 2012.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"c-tab-content__item\" data-tabs=\"content\"><div class=\"c-tab-content\">\n    <p><strong>Premier cycle :<\/strong><\/p>\n    <ul>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">SCO24110<\/a> Certification: concepts de base et contr\u00f4le interne<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">SCO24210<\/a> Certification: int\u00e9gration<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">SCO31710<\/a> Expertise comptable<\/li>\n            <\/ul>\n    <p><strong>Deuxi\u00e8me cycle :<\/strong><\/p>\n    <ul>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">DSC62314<\/a> \u00c9thique professionnelle et certification<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">DSC67014<\/a> S\u00e9minaire d&#8217;int\u00e9gration en comptabilit\u00e9 g\u00e9n\u00e9rale et de gestion<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">GPE75124<\/a> Essai<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">GPE80021<\/a> Co\u00fbts et d\u00e9cisions en gestion des personnes en milieu de travail<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">MGP708X<\/a> Th\u00e8mes sp\u00e9ciaux<\/li>\n                    <li><a target=\"_blank\" href=\"\" rel=\"noopener noreferrer\" class=\"no-barba\" aria-label=\"Ouvre dans une nouvelle fen\u00eatre\" tabindex=\"0\">SCO70121<\/a> Activit\u00e9 de synth\u00e8se<\/li>\n            <\/ul>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/section>\n","protected":false},"featured_media":25481,"template":"","departement_personnes":[262],"class_list":["post-18756","personnes","type-personnes","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes\/18756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes"}],"about":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/types\/personnes"}],"version-history":[{"count":10,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes\/18756\/revisions"}],"predecessor-version":[{"id":53136,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/personnes\/18756\/revisions\/53136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/media\/25481"}],"wp:attachment":[{"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/media?parent=18756"}],"wp:term":[{"taxonomy":"departement_personnes","embeddable":true,"href":"https:\/\/www.uqar.ca\/en\/wp-json\/wp\/v2\/departement_personnes?post=18756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}